{"id":12,"date":"2012-05-02T15:56:44","date_gmt":"2012-05-02T20:56:44","guid":{"rendered":"http:\/\/www.veterinariosvs.org\/editores\/?page_id=12"},"modified":"2020-10-20T06:38:05","modified_gmt":"2020-10-20T11:38:05","slug":"envios","status":"publish","type":"page","link":"https:\/\/www.veterinariosvs.org\/editorial\/envios\/","title":{"rendered":"Publica con Nosotros"},"content":{"rendered":"\n<p><a rel=\"noreferrer noopener\" href=\"https:\/\/forms.gle\/FiHoAeudSKsvMhrB6\" target=\"_blank\">Env\u00edanos tu obra a trav\u00e9s del formulario<\/a> para que nuestro grupo editorial pueda revisarla (debes tener un usuario de Google apps para poder enviar tu obra).  Si la obra pesa m\u00e1s de 10MB por favor escr\u00edbenos a trav\u00e9s del <a href=\"https:\/\/www.veterinariosvs.org\/editorial\/300f0-contact\/\">formulario de contacto<\/a> para indicarte c\u00f3mo y a d\u00f3nde enviarla. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Recuerda<\/h3>\n\n\n\n<ul><li><a href=\"http:\/\/www.veterinariosvs.org\/editorial\/normas\/\">Ver las normas de publicaci\u00f3n VVS [+]<\/a><\/li><li><a href=\"http:\/\/www.ncbi.nlm.nih.gov\/books\/bv.fcgi?rid=citmed.TOC&amp;depth=2\" target=\"_blank\" rel=\"noreferrer noopener\">Consultar las normas de Citaci\u00f3n NLM [+]<\/a><\/li><li><a href=\"http:\/\/www.veterinariosvs.org\/editorial\/envios\/guias\/\">Descargar nuestras gu\u00edas de muestra [+]<\/a><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Env\u00edanos tu obra a trav\u00e9s del formulario para que nuestro grupo editorial pueda revisarla (debes tener un usuario de Google apps para poder enviar tu obra). Si la obra pesa m\u00e1s de 10MB por favor escr\u00edbenos a trav\u00e9s del formulario de contacto para indicarte c\u00f3mo y a d\u00f3nde enviarla. Recuerda Ver las normas de publicaci\u00f3n&hellip;&nbsp;<a href=\"https:\/\/www.veterinariosvs.org\/editorial\/envios\/\" class=\"\" rel=\"bookmark\">Leer m\u00e1s &raquo;<span class=\"screen-reader-text\">Publica con Nosotros<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"_links":{"self":[{"href":"https:\/\/www.veterinariosvs.org\/editorial\/wp-json\/wp\/v2\/pages\/12"}],"collection":[{"href":"https:\/\/www.veterinariosvs.org\/editorial\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.veterinariosvs.org\/editorial\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.veterinariosvs.org\/editorial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.veterinariosvs.org\/editorial\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":5,"href":"https:\/\/www.veterinariosvs.org\/editorial\/wp-json\/wp\/v2\/pages\/12\/revisions"}],"predecessor-version":[{"id":740,"href":"https:\/\/www.veterinariosvs.org\/editorial\/wp-json\/wp\/v2\/pages\/12\/revisions\/740"}],"wp:attachment":[{"href":"https:\/\/www.veterinariosvs.org\/editorial\/wp-json\/wp\/v2\/media?parent=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}